{"id":4189,"date":"2023-12-13T22:23:18","date_gmt":"2023-12-13T22:23:18","guid":{"rendered":"https:\/\/benvenutobrugge.be\/informativa-sulla-privacy\/"},"modified":"2024-02-07T13:54:02","modified_gmt":"2024-02-07T13:54:02","slug":"informativa-sulla-privacy","status":"publish","type":"page","link":"https:\/\/benvenutobrugge.be\/it\/informativa-sulla-privacy\/","title":{"rendered":"Informativa sulla privacy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4189\" class=\"elementor elementor-4189 elementor-3864\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26ee6a7 e-flex e-con-boxed e-con e-parent\" data-id=\"26ee6a7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb8eac8 elementor-widget elementor-widget-text-editor\" data-id=\"cb8eac8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Dettagli di contatto Benvenuto Brugge<\/h2>\n<p>Benvenuto Brugge, con sede in Sint-Amandsstraat 9, 8000 Brugge, \u00e8 responsabile del trattamento dei dati personali come indicato nella presente informativa sulla privacy.<\/p>\n<p><strong>Dettagli di contatto:<\/strong><br \/>Sint-Amandsstraat 9, 8000 Brugge<br \/><a href=\"tel:+3250667418\">+32 50 66 74 18<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a13147e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a13147e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cd7945 elementor-widget elementor-widget-text-editor\" data-id=\"8cd7945\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Dati personali trattati<\/h2>\n<p>Benvenuto Brugge tratta i vostri dati personali perch\u00e9 utilizzate i nostri servizi e\/o perch\u00e9 ce li fornite voi stessi.<br \/>\nDi seguito una panoramica dei dati personali che trattiamo: <\/p>\n<ul>\n<li>Nome e cognome<\/li>\n<li>Numero di telefono<\/li>\n<li>Indirizzo e-mail<\/li>\n<li>Indirizzo IP<\/li>\n<li>Dati sulla posizione<\/li>\n<li>Dati sulle vostre attivit\u00e0 sul nostro sito web<\/li>\n<li>Browser Internet e tipo di dispositivo<\/li>\n<\/ul>\n<h2>Dati personali speciali e\/o sensibili che trattiamo<\/h2>\n<p>Il nostro sito web e\/o servizio non intende raccogliere dati su visitatori di et\u00e0 inferiore ai 16 anni, a meno che non abbiano l&#8217;autorizzazione dei genitori o del tutore.<br \/>\nTuttavia, non possiamo verificare se un visitatore ha pi\u00f9 di 16 anni.<br \/>\nConsigliamo pertanto ai genitori di partecipare alle attivit\u00e0 online dei propri figli per evitare che vengano raccolti dati sui minori senza il consenso dei genitori.<br \/>\nSe siete convinti che abbiamo raccolto informazioni personali su un minore senza tale consenso, contattateci all&#8217;indirizzo <a href=\"mailto:info@benvenutobrugge.be\">info@benvenutobrugge.be<\/a> e provvederemo a cancellare tali informazioni.   <\/p>\n<h2>Finalit\u00e0 e basi per il trattamento dei dati personali<\/h2>\n<p>Benvenuto Brugge tratta i vostri dati personali per le seguenti finalit\u00e0:<\/p>\n<ul>\n<li>Per potervi chiamare o inviare un&#8217;e-mail, se necessario, per gestire la vostra prenotazione.<\/li>\n<\/ul>\n<h2>Processo decisionale automatizzato<\/h2>\n<p>Benvenuto Brugge si assume #responsabilit\u00e0 in base a decisioni di elaborazione automatizzata su questioni che possono avere conseguenze (significative) per le persone.<br \/>\nSi tratta di decisioni prese da programmi o sistemi informatici, senza l&#8217;intervento di una persona (ad esempio un dipendente di Benvenuto Brugge).<br \/>\nBenvenuto Brugge utilizza i seguenti programmi o sistemi informatici: #utilizzo_spiegazione  <\/p>\n<h2>Per quanto tempo conserviamo i dati personali<\/h2>\n<p>Benvenuto Brugge non conserva i vostri dati personali pi\u00f9 a lungo di quanto sia strettamente necessario per raggiungere gli scopi per cui sono stati raccolti.<br \/>\nUtilizziamo i seguenti periodi di conservazione per le seguenti (categorie) di dati personali: #periodo_di_conservazione <\/p>\n<h2>Condivisione dei dati personali con terzi<\/h2>\n<p>Benvenuto Brugge li fornisce solo a terzi e solo se ci\u00f2 \u00e8 necessario per l&#8217;esecuzione del nostro accordo con voi o per adempiere a un obbligo legale.<\/p>\n<h2>Cookie, o tecniche simili, che utilizziamo<\/h2>\n<p>Benvenuto Brugge utilizza cookie funzionali, analitici e di monitoraggio.<br \/>\nUn cookie \u00e8 un piccolo file di testo che viene memorizzato nel browser del vostro computer, tablet o smartphone durante la prima visita a questo sito web.<br \/>\nBenvenuto Brugge utilizza cookie con funzionalit\u00e0 puramente tecniche.<br \/>\nQuesti cookie garantiscono il corretto funzionamento del sito web e, ad esempio, la memorizzazione delle impostazioni preferite.<br \/>\nQuesti cookie sono utilizzati anche per far funzionare bene il sito web e per ottimizzarlo.<br \/>\nInoltre, inseriamo cookie che tracciano il vostro comportamento di navigazione per potervi offrire contenuti e pubblicit\u00e0 personalizzati.<br \/>\nDurante la vostra prima visita al nostro sito web, vi abbiamo gi\u00e0 informato di questi cookie e vi abbiamo chiesto il consenso per inserirli.<br \/>\n\u00c8 possibile rinunciare ai cookie impostando il proprio browser Internet in modo che non li memorizzi pi\u00f9.<br \/>\nInoltre, \u00e8 possibile cancellare tutte le informazioni precedentemente salvate attraverso le impostazioni del browser.<br \/>\nPer una spiegazione, visitare il sito <a style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif;font-weight: var( --e-global-typography-text-font-weight );text-align: var(--text-align);background-color: #ffffff;font-size: 1rem\" href=\"https:\/\/www.gegevensbeschermingsautoriteit.be\/burger\/thema-s\/internet\/cookies.\" target=\"_blank\" rel=\"noopener\">gegevensbeschermingsautoriteit.be.<\/a>         <\/p>\n<h2>Modifica, modifica o eliminazione dei dati<\/h2>\n<p>Avete il diritto di visualizzare, correggere o cancellare i vostri dati personali.<br \/>\nInoltre, avete il diritto di revocare il vostro consenso al trattamento dei dati o di opporvi al trattamento dei vostri dati personali da parte di Benvenuto Brugge, e avete il diritto alla portabilit\u00e0 dei dati.<br \/>\nCi\u00f2 significa che potete richiedere a Benvenuto Brugge di inviare i dati personali in nostro possesso in un archivio informatico a voi o a un&#8217;altra organizzazione da voi indicata.<br \/>\nPotete inviare una richiesta di accesso, correzione, cancellazione, trasferimento dei vostri dati personali o una richiesta di revoca del vostro consenso o di opposizione al trattamento dei vostri dati personali a <a href=\"mailto:info@benvenutobrugge.be\">info@benvenutobrugge.be.<\/a>    Per essere certi che la richiesta di accesso sia stata fatta da voi, vi chiediamo di inviare una copia del vostro documento d&#8217;identit\u00e0 insieme alla richiesta.<br \/>\nIn questa copia, oscurare la foto del passaporto, la MRZ (zona a lettura ottica, la striscia con i numeri nella parte inferiore del passaporto), il numero del passaporto e il numero di servizio del cittadino (BSN).<br \/>\nQuesto per proteggere la vostra privacy.<br \/>\nSu vostra richiesta, vi risponderemo il prima possibile, e comunque entro quattro settimane.<br \/>\nBenvenuto Brugge desidera inoltre sottolineare che avete la possibilit\u00e0 di presentare un reclamo all&#8217;autorit\u00e0 di controllo nazionale, l&#8217;Autorit\u00e0 per i dati personali.<br \/>\nPer farlo, visitate il sito <a href=\"https:\/\/www.gegevensbeschermingsautoriteit.be\/burger\" target=\"_blank\" rel=\"noopener\">gegevensbeschermingsautoriteit.be.<\/a>     <\/p>\n<h2>Come proteggiamo i dati personali<\/h2>\n<p>Benvenuto Brugge prende sul serio la protezione dei vostri dati e adotta misure adeguate per prevenire l&#8217;uso improprio, la perdita, l&#8217;accesso non autorizzato, la divulgazione indesiderata e la modifica non autorizzata.<br \/>\nSe avete l&#8217;impressione che i vostri dati non siano ben protetti o se ci sono indizi di un abuso, vi preghiamo di contattare il nostro servizio clienti o l&#8217;indirizzo <a href=\"mailto:info@benvenutobrugge.be\">info@benvenutobrugge.be.<\/a> <\/p>\n<p><a href=\"https:\/\/benvenutobrugge.be\/it\/informativa-sui-cookie\/\">Visualizza la nostra politica sui cookie<\/a><br \/><a href=\"https:\/\/benvenutobrugge.be\/it\/dichiarazione-di-non-responsabilita\/\">Visualizza la nostra clausola di esclusione della responsabilit\u00e0<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dettagli di contatto Benvenuto Brugge Benvenuto Brugge, con sede in Sint-Amandsstraat 9, 8000 Brugge, \u00e8 responsabile del trattamento dei dati personali come indicato nella presente informativa sulla privacy. Dettagli di contatto:Sint-Amandsstraat 9, 8000 Brugge+32 50 66 74 18 Dati personali trattati Benvenuto Brugge tratta i vostri dati personali perch\u00e9 utilizzate i nostri servizi e\/o perch\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-4189","page","type-page","status-publish","hentry"],"acf":[],"rankMath":{"parentDomain":"benvenutobrugge.be","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"L&#039;immagine in evidenza dovrebbe essere di almeno 200 x 200 pixel per essere ripresa da Facebook e altri siti di social media.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"informativa-sulla-privacy","permalinkFormat":"https:\/\/benvenutobrugge.be\/it\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/benvenutobrugge.be\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"nome utente","primaryTerm":0,"authorName":"admin","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":false,"hasBreadcrumb":false},"homeUrl":"https:\/\/benvenutobrugge.be\/it\/","objectID":4189,"objectType":"post","locale":"it","localeFull":"it_IT","overlayImages":{"play":{"name":"Icona di riproduzione","url":"https:\/\/benvenutobrugge.be\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/data\/sites\/web\/benvenutobruggebe\/www\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Icona GIF","url":"https:\/\/benvenutobrugge.be\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/data\/sites\/web\/benvenutobruggebe\/www\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/benvenutobrugge.be\/wp-content\/uploads\/2023\/11\/Benvenutobrugge-logo-short.webp","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fbenvenutobrugge.be%2Fit%2F&r=https%3A%2F%2Fbenvenutobrugge.be%2Fit%2Fwp-json%2Fwp%2Fv2%2Fpages%2F4189%3Fnonce%3Dac6d32b34e","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/benvenutobrugge.be\/wp-content\/uploads\/2023\/12\/cropped-benvenutobrugge-favicon-scaled-2-32x32.webp","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Aggiorna","trendsPreviewImage":"https:\/\/benvenutobrugge.be\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/benvenutobrugge.be\/it\/wp-json\/wp\/v2\/pages\/4189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/benvenutobrugge.be\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/benvenutobrugge.be\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/benvenutobrugge.be\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/benvenutobrugge.be\/it\/wp-json\/wp\/v2\/comments?post=4189"}],"version-history":[{"count":4,"href":"https:\/\/benvenutobrugge.be\/it\/wp-json\/wp\/v2\/pages\/4189\/revisions"}],"predecessor-version":[{"id":5634,"href":"https:\/\/benvenutobrugge.be\/it\/wp-json\/wp\/v2\/pages\/4189\/revisions\/5634"}],"wp:attachment":[{"href":"https:\/\/benvenutobrugge.be\/it\/wp-json\/wp\/v2\/media?parent=4189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}